{"id":33822,"date":"2020-08-19T22:35:00","date_gmt":"2020-08-20T01:35:00","guid":{"rendered":"http:\/\/culturalizabh.com.br\/?p=33822"},"modified":"2020-08-19T22:35:00","modified_gmt":"2020-08-20T01:35:00","slug":"arena-drive-in-go-dream","status":"publish","type":"post","link":"https:\/\/culturalizabh.com.br\/index.php\/2020\/08\/19\/arena-drive-in-go-dream\/","title":{"rendered":"Arena drive-in Go Dream"},"content":{"rendered":"<p>Esta semana a divers\u00e3o come\u00e7ou mais cedo na <strong>arena<\/strong> <strong>drive-in<\/strong> com programa\u00e7\u00e3o gratuita do <strong>Festival<\/strong> <strong>Desperta<\/strong>, assinado pela Unimed-BH.\u00a0Desde o \u00faltimo domingo, 16, o projeto assinado pela Unimed-BH promove apresenta\u00e7\u00f5es gratuitas ao p\u00fablico, com ingressos retirados previamente pela plataforma Sympla. Na ter\u00e7a-feira, foi dia do sensacional projeto\u00a0<strong>Nie Myer<\/strong>, composto por Henrique Portugal, Lelo e Anderson Noise sobe ao palco. J\u00e1 na quarta-feira, a noite ficou por conta de stand up com os comediantes\u00a0Paloma Santos, Tiago Carmona e Bruno Costoli.<\/p>\n<p>&nbsp;<\/p>\n<p>A programa\u00e7\u00e3o volta na sexta-feira com <strong>D.P.A. Berenice em Perigo<\/strong>, o filme <strong>Os Normais<\/strong> e show da banda <strong>Classic<\/strong>, abaixo programa\u00e7\u00e3o completa para aproveitarmos nosso fim de semana em \u00f3tima companhia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROGRAMA\u00c7\u00c3O:<\/strong><\/p>\n<p><strong>Sexta \u2013 21\/08<\/strong><\/p>\n<p>17h \u2013 Sess\u00e3o Gloob: D.P.A. Berenice em Perigo<\/p>\n<p>19h \u2013 Sess\u00e3o Globo Filmes: Os Normais<\/p>\n<p>21h \u2013 Show: Classics<\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00e1bado \u2013 22\/08<\/strong><\/p>\n<p>18h \u2013 Sess\u00e3o Gloob: D.P.A. 2 \u2013 O mist\u00e9rio italiano<\/p>\n<p>20h30 \u2013 Show: No Label<\/p>\n<p>22h30- \u2013 Sess\u00e3o Telecine \u2013 Minha vida em Marte<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domingo \u2013 23\/08<\/strong><\/p>\n<p>09h &#8211; FESTIVAL DESPERTA UNIMED-BH: Cora\u00e7\u00e3o Palpita + Trampulim &#8211; Uma Surpresa para Benedita<\/p>\n<p>17h \u2013 Madagascar 3<\/p>\n<p>19h \u2013 NBA \u2013 Jogo de Basquete<\/p>\n<p>22h \u2013 Globoplay pr\u00e9-estreia Dentro da Minha Pele<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>SERVI\u00c7O GO DREAM NOVA LIMA:<\/u><\/strong><\/p>\n<p>Sexta-feira: sess\u00f5es \u00e0s 19h e 21h<\/p>\n<p>S\u00e1bado: sess\u00f5es \u00e0s 18h, 20h30 e 22h30<\/p>\n<p>ESPECIAL ARENA GO DREAM UNIMED-BH &#8211; Domingo: sess\u00e3o \u00e0s 9h<\/p>\n<p>Domingo: sess\u00f5es \u00e0s 17h, 19h e 22h<\/p>\n<p><strong>Local:<\/strong>\u00a0Universidade Milton Campos<\/p>\n<p>Capacidade: 100 carros por sess\u00e3o<\/p>\n<p><strong>Valores:<\/strong><\/p>\n<p>FESTIVAL DESPERTA:<\/p>\n<p>Ter\u00e7a, quarta e domingo: gratuito mediante retirada de convites limitados via Sympla<\/p>\n<p><strong>Programa\u00e7\u00e3o gratuita. Ingressos podem ser retirados na plataforma do Sympla:\u00a0<\/strong><a href=\"https:\/\/www.sympla.com.br\/festivaldesperta\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.sympla.com.br\/festivaldesperta&amp;source=gmail&amp;ust=1597971067813000&amp;usg=AFQjCNE3_OLPEDKv-wnnZRgGSGUHTFVGQA\">https:\/\/www.sympla.com.br\/festivaldesperta<\/a><\/p>\n<p>Sexta-feira:\u00a0R$ 70 (meia-entrada e meia solid\u00e1ria*)<\/p>\n<p>S\u00e1bado:\u00a0R$ 90 (meia-entrada e meia solid\u00e1ria*)<\/p>\n<p>Domingo:\u00a0R$ 70 (meia-entrada e meia solid\u00e1ria*)<\/p>\n<p>Vendas de Ingressos e programa\u00e7\u00e3o:\u00a0<a href=\"https:\/\/word-edit.officeapps.live.com\/we\/www.godreambrasil.com.br\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/word-edit.officeapps.live.com\/we\/www.godreambrasil.com.br&amp;source=gmail&amp;ust=1597971067813000&amp;usg=AFQjCNGJyIEcv7T3osKjQgLOAWwtPflI2A\">www.godreambrasil.com.br<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>*\u00a0Ao optar pela modalidade \u201cmeia entrada solid\u00e1ria\u201d, o comprador garante o benef\u00edcio do desconto, mediante o acr\u00e9scimo de uma doa\u00e7\u00e3o no valor de R$5,00. Todas as doa\u00e7\u00f5es ser\u00e3o destinadas para o projeto \u201cFome de M\u00fasica\u201d, uma campanha que contribui para o combate da fome arrecadando recursos para distribui\u00e7\u00e3o de alimentos aos brasileiros em situa\u00e7\u00e3o de extrema vulnerabilidade em meio \u00e0 pandemia. Para saber mais, acesse\u00a0<a href=\"https:\/\/www.fomedemusica.com\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fomedemusica.com\/&amp;source=gmail&amp;ust=1597971067813000&amp;usg=AFQjCNHNUuLhV-32g2uCON45Tq_ZhlnEiQ\">https:\/\/www.fomedemusica.com\/<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana a divers\u00e3o come\u00e7ou mais cedo na arena drive-in com programa\u00e7\u00e3o gratuita do Festival Desperta, assinado pela Unimed-BH.\u00a0Desde o \u00faltimo domingo, 16, o projeto assinado pela Unimed-BH promove apresenta\u00e7\u00f5es gratuitas ao p\u00fablico, com ingressos retirados previamente pela plataforma Sympla. Na ter\u00e7a-feira, foi dia do sensacional projeto\u00a0Nie Myer, composto por Henrique Portugal, Lelo e Anderson [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":33823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1,34,8974,3537],"tags":[9469,425,9468],"class_list":["post-33822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culturaliza","category-diversao","category-quarentena","category-gratuito-ou-a-baixo-custo","tag-arena-go-dream-unimed-bh","tag-culturalizabh","tag-festival-desperta"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/culturalizabh.com.br\/wp-content\/uploads\/2020\/08\/Go-Dream-BH-crd-Phillipe-Guimaraes-BS-Fotografias-2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p864jz-8Nw","_links":{"self":[{"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33822"}],"version-history":[{"count":1,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33822\/revisions"}],"predecessor-version":[{"id":33824,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33822\/revisions\/33824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/media\/33823"}],"wp:attachment":[{"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/culturalizabh.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}